{"id":7172,"date":"2015-12-05T14:36:36","date_gmt":"2015-12-05T16:36:36","guid":{"rendered":"http:\/\/blog.panrotas.com.br\/direto-de-paris\/?p=2339"},"modified":"2015-12-05T14:36:36","modified_gmt":"2015-12-05T16:36:36","slug":"sua-energia-para-iluminar-a-torre-eiffel","status":"publish","type":"post","link":"https:\/\/blog.panrotas.com.br\/direto-de-paris\/2015\/12\/05\/sua-energia-para-iluminar-a-torre-eiffel\/","title":{"rendered":"Sua energia para iluminar a Torre Eiffel"},"content":{"rendered":"<p>Entre os dias\u00a06\u00a0e 12 de dezembro de 2015, os cidad\u00e3os de todo o mundo ser\u00e3o capazes de iluminar a obra de arte instalada na Torre Eiffel:<\/p>\n<ul>\n<li>Gra\u00e7as \u00e0 energia f\u00edsica: fazendo esporte e contando a energia cal\u00f3rica gasta atrav\u00e9s da aplica\u00e7\u00e3o RUNTASTIC<\/li>\n<li>Gra\u00e7as \u00e0 energia do pensamento: usando o hashtag #COP21 #HumanEnergy #Climatesign #ParisClimat2015 e #ClimateChange no Twitter Hashtags.<\/li>\n<\/ul>\n<p><strong>Durante a COP 21, Torre Eiffel vira a maior obra de arte participativa do mundo. <\/strong><strong><br \/>\n<\/strong>Um medidor de energia e o Climate Sign ser\u00e3o vis\u00edveis na parte inferior ou \u201cna saia\u201d da Torre.<br \/>\n24 projetores ser\u00e3o instalados no terceiro andar, eles redistribuir\u00e3o a energia implantada por todos aqueles que querem investir de seu tempo agindo pelo planeta.<\/p>\n<p>Como acontece? Esta energia f\u00edsica e cognitiva \u00e9 reconhecida como unidades de energia art\u00edstica e exibida no medidor instalado na Torre Eiffel. Chegando ao limite de 999 milh\u00f5es unidades de energia art\u00edstica, o fluxo transforma-se em uma monumental distribui\u00e7\u00e3o de faixos luminosos a partir da parte superior da Torre Eiffel.<\/p>\n<p>O artista franc\u00eas Yann Toma, em colabora\u00e7\u00e3o com a ag\u00eancia de cenografia e design ARTEL, transformar\u00e1 a Torre Eiffel em uma enorme antena de energia humana: HUMAN ENERGY quer chamar a aten\u00e7\u00e3o para o estado de emerg\u00eancia clim\u00e1tico. Este gerador de poder humano monumental reconhecer\u00e1 a energia cal\u00f3rica produzida por 75 milh\u00f5es de esportistas no mundo, gra\u00e7as \u00e0 aplica\u00e7\u00e3o RUNTASTIC e a energia cognitiva produzida na terra, pela contagem de tweets gerados pela COP21. Esta Obra-luz traz uma mensagem positiva sobre a mudan\u00e7a clim\u00e1tica: pequenas a\u00e7\u00f5es individuais sejam elas naturais ou intencionais, se re\u00fanem em um projeto coletivo agindo em favor do clima.<\/p>\n<p>Human Energie em 7 dias: 75 milh\u00f5es registrados em RUNTASTIC<br \/>\n284 milh\u00f5es de calorias queimadas por dia<br \/>\n1 bilh\u00e3o de tweets COP 21 gerado em 7 dias<br \/>\nA Torre Eiffel, s\u00edmbolo global de compromisso clim\u00e1tico.<\/p>\n<p>\u201cQuero mostrar o quanto as for\u00e7as do corpo e da mente podem se colocar ao servi\u00e7o de um comprometimento civico em rela\u00e7\u00e3o ao clima. A Torre Eiffel \u00e9 um s\u00edmbolo que tem um enorme poder de atra\u00e7\u00e3o do mundo. Gostaria de faz\u00ea-lo brilhar o iluminando com a energia f\u00edsica e cognitiva, desenvolvida durante o COP21. A Torre Eiffel, portanto, sera transformada em uma antena de energia monumental que se tornara o sinal do nosso compromisso com o clima\u201d Yann Toma, artista-observador nas Na\u00e7\u00f5es Unidas<\/p>\n<p>fonte : Torre\u00a0Eiffel<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Entre os dias\u00a06\u00a0e 12 de dezembro de 2015, os cidad\u00e3os de todo o mundo ser\u00e3o capazes de iluminar a obra de arte instalada na Torre Eiffel: Gra\u00e7as \u00e0 energia f\u00edsica: fazendo esporte e contando a energia cal\u00f3rica gasta atrav\u00e9s da aplica\u00e7\u00e3o RUNTASTIC Gra\u00e7as \u00e0 energia do pensamento: usando o hashtag #COP21 #HumanEnergy #Climatesign #ParisClimat2015 e&hellip; <a class=\"more-link\" href=\"https:\/\/blog.panrotas.com.br\/direto-de-paris\/2015\/12\/05\/sua-energia-para-iluminar-a-torre-eiffel\/\">Continue reading &rarr;<\/a><\/p>\n","protected":false},"author":15,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[44],"tags":[],"_links":{"self":[{"href":"https:\/\/blog.panrotas.com.br\/direto-de-paris\/wp-json\/wp\/v2\/posts\/7172"}],"collection":[{"href":"https:\/\/blog.panrotas.com.br\/direto-de-paris\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.panrotas.com.br\/direto-de-paris\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog.panrotas.com.br\/direto-de-paris\/wp-json\/wp\/v2\/users\/15"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.panrotas.com.br\/direto-de-paris\/wp-json\/wp\/v2\/comments?post=7172"}],"version-history":[{"count":0,"href":"https:\/\/blog.panrotas.com.br\/direto-de-paris\/wp-json\/wp\/v2\/posts\/7172\/revisions"}],"wp:attachment":[{"href":"https:\/\/blog.panrotas.com.br\/direto-de-paris\/wp-json\/wp\/v2\/media?parent=7172"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.panrotas.com.br\/direto-de-paris\/wp-json\/wp\/v2\/categories?post=7172"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.panrotas.com.br\/direto-de-paris\/wp-json\/wp\/v2\/tags?post=7172"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}