{"id":118,"date":"2016-08-13T13:01:43","date_gmt":"2016-08-13T16:01:43","guid":{"rendered":"http:\/\/blog.panrotas.com.br\/diretodabahia\/?p=118"},"modified":"2019-05-17T17:54:13","modified_gmt":"2019-05-17T20:54:13","slug":"a-reinvencao-do-chocolate-e-de-uma-cidade-inteira","status":"publish","type":"post","link":"https:\/\/blog.panrotas.com.br\/diretodabahia\/2016\/08\/13\/a-reinvencao-do-chocolate-e-de-uma-cidade-inteira\/","title":{"rendered":"A Reinven\u00e7\u00e3o do Chocolate (e de uma cidade inteira)"},"content":{"rendered":"<p>As primeiras sementes de cacau chegaram na Bahia em meados do s\u00e9culo XVIII. Trazidas diretamente da Amaz\u00f4nia, o fruto encontrou na Mata Atl\u00e2ntica um ambiente ideal para o seu desenvolvimento. Por aqui, o sistema de cultivo ganhou o nome de \u201ccabruca\u201d, no qual os p\u00e9s de cacau s\u00e3o plantados dentro da mata j\u00e1 existente, garantindo a preserva\u00e7\u00e3o ecol\u00f3gica do lugar. Com o passar do tempo, muita gente &#8211; ou melhor, pouca \u2013 fez BASTANTE fortuna com o seu cultivo, e toda uma regi\u00e3o passou a existir em fun\u00e7\u00e3o do fruto.<\/p>\n<p><img loading=\"lazy\" class=\"aligncenter size-full wp-image-119\" src=\"http:\/\/panrotas.blog.br\/diretodabahia\/wp-content\/uploads\/sites\/4\/2016\/08\/IMG_2196.jpg\" alt=\"IMG_2196\" width=\"1024\" height=\"768\" srcset=\"https:\/\/blog.panrotas.com.br\/diretodabahia\/wp-content\/uploads\/sites\/4\/2016\/08\/IMG_2196.jpg 1024w, https:\/\/blog.panrotas.com.br\/diretodabahia\/wp-content\/uploads\/sites\/4\/2016\/08\/IMG_2196-300x225.jpg 300w, https:\/\/blog.panrotas.com.br\/diretodabahia\/wp-content\/uploads\/sites\/4\/2016\/08\/IMG_2196-768x576.jpg 768w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/p>\n<p>Ilh\u00e9us, que at\u00e9 ent\u00e3o n\u00e3o passava de uma vila, \u00e9 elevada \u00e0 categoria de cidade no final s\u00e9culo XIX, e entra num ritmo acelerado de urbaniza\u00e7\u00e3o e crescimento econ\u00f4mico, marcados pelo luxo e a ostenta\u00e7\u00e3o dos lend\u00e1rios coron\u00e9is do cacau. Esse apogeu, que se destacou entre as d\u00e9cadas de 20 e 40 do s\u00e9culo passado, trouxe novos empreendimentos para a regi\u00e3o e colocou a regi\u00e3o no mapa, atraindo gente de todo o mundo para a chamada \u201cPrincesinha do Sul da Bahia\u201d.<\/p>\n<p>Tudo girava em torno do cacau. A cidade gerava tanta riqueza para a Bahia, que at\u00e9 a folha de pagamento dos funcion\u00e1rios do Estado s\u00f3 era fechada ap\u00f3s a exporta\u00e7\u00e3o das sacas. Por v\u00e1rias d\u00e9cadas, a regi\u00e3o de Ilh\u00e9us manteve o Brasil no topo dos produtores de cacau mundiais. O Bataclan, o Bar Ves\u00favio, a Catedral de S\u00e3o Sebasti\u00e3o, o Teatro Municipal, o Pal\u00e1cio Paranagu\u00e1 e os v\u00e1rios palacetes, casar\u00f5es e fazendas da \u00e9poca \u00e1urea do cacau ainda est\u00e3o l\u00e1, como mem\u00f3ria viva do per\u00edodo \u2013 \u00e9 emblem\u00e1tico o caso de um coronel que mandou pavimentar a pr\u00f3pria rua com pedras polidas na Europa. Nos anos 50, o escritor Jorge Amado \u2013 tamb\u00e9m filho de um coronel \u2013 publica \u201cGabriela Cravo e Canela\u201d, seu mais famoso romance. Em 1957, surge a CEPLAC (Comiss\u00e3o Executiva do Plano da Lavoura Cacaueira), como apoio para os produtores locais. E nos anos 80, chega a vassoura de bruxa.<\/p>\n<p style=\"text-align: center\"><em>Diga aonde o cacau vai, que eu vou varrendo<\/em><\/p>\n<p><img loading=\"lazy\" class=\"aligncenter size-full wp-image-120\" src=\"http:\/\/panrotas.blog.br\/diretodabahia\/wp-content\/uploads\/sites\/4\/2016\/08\/IMG_2249.jpg\" alt=\"IMG_2249\" width=\"1024\" height=\"768\" srcset=\"https:\/\/blog.panrotas.com.br\/diretodabahia\/wp-content\/uploads\/sites\/4\/2016\/08\/IMG_2249.jpg 1024w, https:\/\/blog.panrotas.com.br\/diretodabahia\/wp-content\/uploads\/sites\/4\/2016\/08\/IMG_2249-300x225.jpg 300w, https:\/\/blog.panrotas.com.br\/diretodabahia\/wp-content\/uploads\/sites\/4\/2016\/08\/IMG_2249-768x576.jpg 768w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/p>\n<p>S\u00e3o muitas as vers\u00f5es que explicam a vers\u00e3o do surgimento da praga da vassoura de bruxa em Ilh\u00e9us. A mais conhecida fala em bioterrorismo, como uma forma de boicote a produtores apadrinhados pela CEPLAC. Esta, por sua vez, nega veementemente, afirmando que o fungo foi trazido por acidente, quando alguns produtores tentaram se arriscar no cultivo do cacau na Amaz\u00f4nia \u2013 e acabaram carregando a doen\u00e7a para a Bahia.<\/p>\n<p><img loading=\"lazy\" class=\"aligncenter size-full wp-image-121\" src=\"http:\/\/panrotas.blog.br\/diretodabahia\/wp-content\/uploads\/sites\/4\/2016\/08\/IMG_2193.jpg\" alt=\"IMG_2193\" width=\"1024\" height=\"768\" srcset=\"https:\/\/blog.panrotas.com.br\/diretodabahia\/wp-content\/uploads\/sites\/4\/2016\/08\/IMG_2193.jpg 1024w, https:\/\/blog.panrotas.com.br\/diretodabahia\/wp-content\/uploads\/sites\/4\/2016\/08\/IMG_2193-300x225.jpg 300w, https:\/\/blog.panrotas.com.br\/diretodabahia\/wp-content\/uploads\/sites\/4\/2016\/08\/IMG_2193-768x576.jpg 768w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/p>\n<p>A vassoura de bruxa devastou in\u00fameras planta\u00e7\u00f5es da regi\u00e3o de Ilh\u00e9us e diminuiu drasticamente a produ\u00e7\u00e3o local. Muitos perderam tudo o que tinham, e fam\u00edlias inteiras de trabalhadores rurais se viram obrigadas a abandonar suas casas nas fazendas. O impacto da praga parecia irrevers\u00edvel, irremedi\u00e1vel e incontrol\u00e1vel.<\/p>\n<p>Para piorar, a grande ind\u00fastria de chocolate, que notadamente n\u00e3o est\u00e1 preocupada com a qualidade do cacau, continuou comprando a safra contaminada \u2013 obviamente por um pre\u00e7o muito inferior \u2013, impossibilitando a renova\u00e7\u00e3o das planta\u00e7\u00f5es. N\u00e3o parecia haver uma luz no fim do t\u00fanel, at\u00e9 que algu\u00e9m teve uma ideia que mudou toda a l\u00f3gica do processo: se a Bahia, mesmo ap\u00f3s a vassoura de bruxa, ainda se mantinha como maior exportadora de cacau do Pa\u00eds, por que n\u00e3o produzirmos aqui mesmo o nosso chocolate?<\/p>\n<p>Antes, vamos entender um pouco como funciona o neg\u00f3cio.<\/p>\n<p style=\"text-align: center\"><em>Tree to bar: o que \u00e9 isso?<\/em><\/p>\n<p><img loading=\"lazy\" class=\"aligncenter size-full wp-image-122\" src=\"http:\/\/panrotas.blog.br\/diretodabahia\/wp-content\/uploads\/sites\/4\/2016\/08\/IMG_2350.jpg\" alt=\"IMG_2350\" width=\"1024\" height=\"768\" srcset=\"https:\/\/blog.panrotas.com.br\/diretodabahia\/wp-content\/uploads\/sites\/4\/2016\/08\/IMG_2350.jpg 1024w, https:\/\/blog.panrotas.com.br\/diretodabahia\/wp-content\/uploads\/sites\/4\/2016\/08\/IMG_2350-300x225.jpg 300w, https:\/\/blog.panrotas.com.br\/diretodabahia\/wp-content\/uploads\/sites\/4\/2016\/08\/IMG_2350-768x576.jpg 768w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/p>\n<p>1 \u2013 O cacaueiro (<em>Theobrama cacao<\/em>) \u00e9 uma planta da fam\u00edlia Malvadece. Das sementes fermentadas s\u00e3o produzidos o l\u00edquor, o cacau em p\u00f3 e a manteiga. E somente em fase posterior do processamento, obt\u00e9m-se o chocolate.<\/p>\n<p>2 \u2013 A colheita deve ser realizada quando os frutos estiverem maduros, e ap\u00f3s, eles s\u00e3o quebrados para a extra\u00e7\u00e3o das sementes.<\/p>\n<p>3 \u2013 Segue-se a fermenta\u00e7\u00e3o das sementes do cacau, cuja dura\u00e7\u00e3o varia de 5 a 7 dias.<\/p>\n<p>4 \u2013 A etapa posterior \u00e9 a secagem, efetuada naturalmente (expostas ao sol), e o armazenamento das sacas at\u00e9 a comercializa\u00e7\u00e3o.<\/p>\n<p><img loading=\"lazy\" class=\"aligncenter size-full wp-image-123\" src=\"http:\/\/panrotas.blog.br\/diretodabahia\/wp-content\/uploads\/sites\/4\/2016\/08\/IMG_2309.jpg\" alt=\"IMG_2309\" width=\"1024\" height=\"768\" srcset=\"https:\/\/blog.panrotas.com.br\/diretodabahia\/wp-content\/uploads\/sites\/4\/2016\/08\/IMG_2309.jpg 1024w, https:\/\/blog.panrotas.com.br\/diretodabahia\/wp-content\/uploads\/sites\/4\/2016\/08\/IMG_2309-300x225.jpg 300w, https:\/\/blog.panrotas.com.br\/diretodabahia\/wp-content\/uploads\/sites\/4\/2016\/08\/IMG_2309-768x576.jpg 768w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/p>\n<p>Pronto. A partir da\u00ed, as sementes eram exportadas, e pa\u00edses como Su\u00ed\u00e7a, B\u00e9lgica e Fran\u00e7a levavam todo o m\u00e9rito pela produ\u00e7\u00e3o do chocolate, num processo popularmente conhecido como <em>beans to bars<\/em> (\u201cdas sementes \u00e0s barras\u201d).<\/p>\n<p>5 \u2013 Ao chegar \u00e0 ind\u00fastria, as am\u00eandoas de cacau s\u00e3o classificadas pela prova de corte. As am\u00eandoas passam por um sistema de peneiras para limpeza e aspira\u00e7\u00e3o de part\u00edculas finas, como p\u00f3 e areia. Entram em cena a torrefa\u00e7\u00e3o, para reduzir a umidade da am\u00eandoa, e a a fragmenta\u00e7\u00e3o e o descascamento, para se obter o chamado \u2018nibs de cacau\u2019.<\/p>\n<p>6 \u2013 A moagem, realizada em um moinho de facas, \u00e9 a etapa seguinte para se chegar ao l\u00edquor (mat\u00e9ria prima principal para a produ\u00e7\u00e3o de chocolate).<\/p>\n<p>7 \u2013 Por fim, o processo segue para o refino, o concheamento e a temperagem. A massa obtida com a t\u00eampera \u00e9 transferida para as formas, e estas s\u00e3o colocadas no t\u00fanel de resfriamento, at\u00e9 a cristaliza\u00e7\u00e3o do chocolate.<\/p>\n<p><img loading=\"lazy\" class=\"aligncenter size-full wp-image-126\" src=\"http:\/\/panrotas.blog.br\/diretodabahia\/wp-content\/uploads\/sites\/4\/2016\/08\/IMG_2348.jpg\" alt=\"IMG_2348\" width=\"1024\" height=\"768\" srcset=\"https:\/\/blog.panrotas.com.br\/diretodabahia\/wp-content\/uploads\/sites\/4\/2016\/08\/IMG_2348.jpg 1024w, https:\/\/blog.panrotas.com.br\/diretodabahia\/wp-content\/uploads\/sites\/4\/2016\/08\/IMG_2348-300x225.jpg 300w, https:\/\/blog.panrotas.com.br\/diretodabahia\/wp-content\/uploads\/sites\/4\/2016\/08\/IMG_2348-768x576.jpg 768w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/p>\n<p>Assim, observando que era apenas uma quest\u00e3o de tempo (ok, e de dinheiro tamb\u00e9m) para que a Bahia sa\u00edsse de mero produtor da mat\u00e9ria prima para comercializar tamb\u00e9m o cobi\u00e7ado produto final. Diante do maior controle sobre todas as etapas de produ\u00e7\u00e3o, o que era um <em>beans to bars<\/em> (\u2018das sementes \u00e0s barras\u2019) nos pa\u00edses europeus, na Bahia \u2013 e em outras regi\u00f5es \u2013 recebeu o nome de <em>tree to bar<\/em> (\u2018da \u00e1rvore \u00e0 barra\u2019).<\/p>\n<p style=\"text-align: center\"><em>Do cacau fino ao chocolate gourmet<\/em><\/p>\n<p><img loading=\"lazy\" class=\"aligncenter size-full wp-image-125\" src=\"http:\/\/panrotas.blog.br\/diretodabahia\/wp-content\/uploads\/sites\/4\/2016\/08\/IMG_2329.jpg\" alt=\"IMG_2329\" width=\"1024\" height=\"768\" srcset=\"https:\/\/blog.panrotas.com.br\/diretodabahia\/wp-content\/uploads\/sites\/4\/2016\/08\/IMG_2329.jpg 1024w, https:\/\/blog.panrotas.com.br\/diretodabahia\/wp-content\/uploads\/sites\/4\/2016\/08\/IMG_2329-300x225.jpg 300w, https:\/\/blog.panrotas.com.br\/diretodabahia\/wp-content\/uploads\/sites\/4\/2016\/08\/IMG_2329-768x576.jpg 768w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/p>\n<p>A vassoura de bruxa ainda incomoda a regi\u00e3o, mas a n\u00edvel de estudos e pesquisas, muito tem sido feito para contornar a praga. Uma das estrat\u00e9gias para o combate \u00e9 a clonagem com exemplares de p\u00e9 de cacau da Amaz\u00f4nia, que n\u00e3o sofriam com a doen\u00e7a mesmo quando expostos ao fungo.<\/p>\n<p>O Sul da Bahia entrou com o p\u00e9 direito na rota do chocolate. Aliando um cacau de qualidade \u2013 que se mede por fatores como origem gen\u00e9tica, manejo, colheita, fermenta\u00e7\u00e3o, etc \u2013 com um crescente desenvolvimento da regi\u00e3o \u2013 onde antes se via apenas fazendas, agora tamb\u00e9m s\u00e3o f\u00e1bricas de chocolate \u2013 dezenas de marcas v\u00eam surgindo para consolidar o Estado inclusive como refer\u00eancia de chocolate gourmet no Brasil.<\/p>\n<p><img loading=\"lazy\" class=\"aligncenter size-full wp-image-124\" src=\"http:\/\/panrotas.blog.br\/diretodabahia\/wp-content\/uploads\/sites\/4\/2016\/08\/IMG_2300.jpg\" alt=\"IMG_2300\" width=\"1024\" height=\"768\" srcset=\"https:\/\/blog.panrotas.com.br\/diretodabahia\/wp-content\/uploads\/sites\/4\/2016\/08\/IMG_2300.jpg 1024w, https:\/\/blog.panrotas.com.br\/diretodabahia\/wp-content\/uploads\/sites\/4\/2016\/08\/IMG_2300-300x225.jpg 300w, https:\/\/blog.panrotas.com.br\/diretodabahia\/wp-content\/uploads\/sites\/4\/2016\/08\/IMG_2300-768x576.jpg 768w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/p>\n<p>Eu n\u00e3o fazia a menor ideia da quantidade de todos os chocolates legitimamente baianos que j\u00e1 existiam no mercado. As receitas podem incluir ingredientes ex\u00f3ticos e porcentagens de cacau alt\u00edssimas para o paladar criado a bombom Caribe, mas \u00e9 tudo uma quest\u00e3o de h\u00e1bito \u2013 afinal de contas, gosto \u00e9 algo que se cria (e quase ningu\u00e9m nasce querendo enfiar chocolate 100% cacau goela abaixo).<\/p>\n<p style=\"text-align: center\"><em>Pra que Gramado?<\/em><\/p>\n<p><img loading=\"lazy\" class=\"aligncenter size-full wp-image-127\" src=\"http:\/\/panrotas.blog.br\/diretodabahia\/wp-content\/uploads\/sites\/4\/2016\/08\/IMG_2317.jpg\" alt=\"IMG_2317\" width=\"1024\" height=\"768\" srcset=\"https:\/\/blog.panrotas.com.br\/diretodabahia\/wp-content\/uploads\/sites\/4\/2016\/08\/IMG_2317.jpg 1024w, https:\/\/blog.panrotas.com.br\/diretodabahia\/wp-content\/uploads\/sites\/4\/2016\/08\/IMG_2317-300x225.jpg 300w, https:\/\/blog.panrotas.com.br\/diretodabahia\/wp-content\/uploads\/sites\/4\/2016\/08\/IMG_2317-768x576.jpg 768w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/p>\n<p>Ilh\u00e9us \u00e9 provavelmente o \u00fanico destino tur\u00edstico do Brasil onde se pode conhecer, de fato, todo o processo de produ\u00e7\u00e3o do chocolate \u2013 desde a planta\u00e7\u00e3o do cacau nas fazendas \u00e0 embalagem das barras nas f\u00e1bricas. Ironicamente, por ser uma regi\u00e3o de clima tropical, o lugar n\u00e3o aparece nos guias de viagem como refer\u00eancia no assunto \u2013 nesse quesito, as indica\u00e7\u00f5es ainda insistem em associar o chocolate apenas a destinos de inverno como a Serra Ga\u00facha. Como se n\u00e3o fosse poss\u00edvel comer chocolate no calor.<\/p>\n<p>Para se ter uma ideia das marcas de chocolate gourmet produzido na Bahia \u2013 um melhor que o outro \u2013, veja a lista abaixo e se pergunte quantos voc\u00ea conhece.<\/p>\n<p><img loading=\"lazy\" class=\"aligncenter size-full wp-image-128\" src=\"http:\/\/panrotas.blog.br\/diretodabahia\/wp-content\/uploads\/sites\/4\/2016\/08\/IMG_7795.jpg\" alt=\"IMG_7795\" width=\"1632\" height=\"1224\" srcset=\"https:\/\/blog.panrotas.com.br\/diretodabahia\/wp-content\/uploads\/sites\/4\/2016\/08\/IMG_7795.jpg 1632w, https:\/\/blog.panrotas.com.br\/diretodabahia\/wp-content\/uploads\/sites\/4\/2016\/08\/IMG_7795-300x225.jpg 300w, https:\/\/blog.panrotas.com.br\/diretodabahia\/wp-content\/uploads\/sites\/4\/2016\/08\/IMG_7795-768x576.jpg 768w, https:\/\/blog.panrotas.com.br\/diretodabahia\/wp-content\/uploads\/sites\/4\/2016\/08\/IMG_7795-1024x768.jpg 1024w, https:\/\/blog.panrotas.com.br\/diretodabahia\/wp-content\/uploads\/sites\/4\/2016\/08\/IMG_7795-1568x1176.jpg 1568w\" sizes=\"(max-width: 1632px) 100vw, 1632px\" \/><\/p>\n<p><img loading=\"lazy\" class=\"aligncenter size-full wp-image-129\" src=\"http:\/\/panrotas.blog.br\/diretodabahia\/wp-content\/uploads\/sites\/4\/2016\/08\/IMG_7449.jpg\" alt=\"IMG_7449\" width=\"1632\" height=\"1224\" srcset=\"https:\/\/blog.panrotas.com.br\/diretodabahia\/wp-content\/uploads\/sites\/4\/2016\/08\/IMG_7449.jpg 1632w, https:\/\/blog.panrotas.com.br\/diretodabahia\/wp-content\/uploads\/sites\/4\/2016\/08\/IMG_7449-300x225.jpg 300w, https:\/\/blog.panrotas.com.br\/diretodabahia\/wp-content\/uploads\/sites\/4\/2016\/08\/IMG_7449-768x576.jpg 768w, https:\/\/blog.panrotas.com.br\/diretodabahia\/wp-content\/uploads\/sites\/4\/2016\/08\/IMG_7449-1024x768.jpg 1024w, https:\/\/blog.panrotas.com.br\/diretodabahia\/wp-content\/uploads\/sites\/4\/2016\/08\/IMG_7449-1568x1176.jpg 1568w\" sizes=\"(max-width: 1632px) 100vw, 1632px\" \/><\/p>\n<p><img loading=\"lazy\" class=\"aligncenter size-full wp-image-130\" src=\"http:\/\/panrotas.blog.br\/diretodabahia\/wp-content\/uploads\/sites\/4\/2016\/08\/IMG_7791.jpg\" alt=\"IMG_7791\" width=\"1632\" height=\"1224\" srcset=\"https:\/\/blog.panrotas.com.br\/diretodabahia\/wp-content\/uploads\/sites\/4\/2016\/08\/IMG_7791.jpg 1632w, https:\/\/blog.panrotas.com.br\/diretodabahia\/wp-content\/uploads\/sites\/4\/2016\/08\/IMG_7791-300x225.jpg 300w, https:\/\/blog.panrotas.com.br\/diretodabahia\/wp-content\/uploads\/sites\/4\/2016\/08\/IMG_7791-768x576.jpg 768w, https:\/\/blog.panrotas.com.br\/diretodabahia\/wp-content\/uploads\/sites\/4\/2016\/08\/IMG_7791-1024x768.jpg 1024w, https:\/\/blog.panrotas.com.br\/diretodabahia\/wp-content\/uploads\/sites\/4\/2016\/08\/IMG_7791-1568x1176.jpg 1568w\" sizes=\"(max-width: 1632px) 100vw, 1632px\" \/><\/p>\n<p><img loading=\"lazy\" class=\"aligncenter size-full wp-image-131\" src=\"http:\/\/panrotas.blog.br\/diretodabahia\/wp-content\/uploads\/sites\/4\/2016\/08\/IMG_7794.jpg\" alt=\"IMG_7794\" width=\"1224\" height=\"1632\" srcset=\"https:\/\/blog.panrotas.com.br\/diretodabahia\/wp-content\/uploads\/sites\/4\/2016\/08\/IMG_7794.jpg 1224w, https:\/\/blog.panrotas.com.br\/diretodabahia\/wp-content\/uploads\/sites\/4\/2016\/08\/IMG_7794-225x300.jpg 225w, https:\/\/blog.panrotas.com.br\/diretodabahia\/wp-content\/uploads\/sites\/4\/2016\/08\/IMG_7794-768x1024.jpg 768w\" sizes=\"(max-width: 1224px) 100vw, 1224px\" \/><\/p>\n<p><img loading=\"lazy\" class=\"aligncenter size-full wp-image-132\" src=\"http:\/\/panrotas.blog.br\/diretodabahia\/wp-content\/uploads\/sites\/4\/2016\/08\/IMG_7801.jpg\" alt=\"IMG_7801\" width=\"1632\" height=\"1224\" srcset=\"https:\/\/blog.panrotas.com.br\/diretodabahia\/wp-content\/uploads\/sites\/4\/2016\/08\/IMG_7801.jpg 1632w, https:\/\/blog.panrotas.com.br\/diretodabahia\/wp-content\/uploads\/sites\/4\/2016\/08\/IMG_7801-300x225.jpg 300w, https:\/\/blog.panrotas.com.br\/diretodabahia\/wp-content\/uploads\/sites\/4\/2016\/08\/IMG_7801-768x576.jpg 768w, https:\/\/blog.panrotas.com.br\/diretodabahia\/wp-content\/uploads\/sites\/4\/2016\/08\/IMG_7801-1024x768.jpg 1024w, https:\/\/blog.panrotas.com.br\/diretodabahia\/wp-content\/uploads\/sites\/4\/2016\/08\/IMG_7801-1568x1176.jpg 1568w\" sizes=\"(max-width: 1632px) 100vw, 1632px\" \/><\/p>\n<p><img loading=\"lazy\" class=\"aligncenter size-full wp-image-133\" src=\"http:\/\/panrotas.blog.br\/diretodabahia\/wp-content\/uploads\/sites\/4\/2016\/08\/FullSizeRender-2.jpg\" alt=\"FullSizeRender (2)\" width=\"1632\" height=\"1224\" srcset=\"https:\/\/blog.panrotas.com.br\/diretodabahia\/wp-content\/uploads\/sites\/4\/2016\/08\/FullSizeRender-2.jpg 1632w, https:\/\/blog.panrotas.com.br\/diretodabahia\/wp-content\/uploads\/sites\/4\/2016\/08\/FullSizeRender-2-300x225.jpg 300w, https:\/\/blog.panrotas.com.br\/diretodabahia\/wp-content\/uploads\/sites\/4\/2016\/08\/FullSizeRender-2-768x576.jpg 768w, https:\/\/blog.panrotas.com.br\/diretodabahia\/wp-content\/uploads\/sites\/4\/2016\/08\/FullSizeRender-2-1024x768.jpg 1024w, https:\/\/blog.panrotas.com.br\/diretodabahia\/wp-content\/uploads\/sites\/4\/2016\/08\/FullSizeRender-2-1568x1176.jpg 1568w\" sizes=\"(max-width: 1632px) 100vw, 1632px\" \/><\/p>\n<p><img loading=\"lazy\" class=\"aligncenter size-full wp-image-134\" src=\"http:\/\/panrotas.blog.br\/diretodabahia\/wp-content\/uploads\/sites\/4\/2016\/08\/FullSizeRender.jpg\" alt=\"FullSizeRender\" width=\"1224\" height=\"1632\" srcset=\"https:\/\/blog.panrotas.com.br\/diretodabahia\/wp-content\/uploads\/sites\/4\/2016\/08\/FullSizeRender.jpg 1224w, https:\/\/blog.panrotas.com.br\/diretodabahia\/wp-content\/uploads\/sites\/4\/2016\/08\/FullSizeRender-225x300.jpg 225w, https:\/\/blog.panrotas.com.br\/diretodabahia\/wp-content\/uploads\/sites\/4\/2016\/08\/FullSizeRender-768x1024.jpg 768w\" sizes=\"(max-width: 1224px) 100vw, 1224px\" \/><\/p>\n<p><img loading=\"lazy\" class=\"aligncenter size-full wp-image-135\" src=\"http:\/\/panrotas.blog.br\/diretodabahia\/wp-content\/uploads\/sites\/4\/2016\/08\/IMG_9993.jpg\" alt=\"IMG_9993\" width=\"1632\" height=\"1224\" srcset=\"https:\/\/blog.panrotas.com.br\/diretodabahia\/wp-content\/uploads\/sites\/4\/2016\/08\/IMG_9993.jpg 1632w, https:\/\/blog.panrotas.com.br\/diretodabahia\/wp-content\/uploads\/sites\/4\/2016\/08\/IMG_9993-300x225.jpg 300w, https:\/\/blog.panrotas.com.br\/diretodabahia\/wp-content\/uploads\/sites\/4\/2016\/08\/IMG_9993-768x576.jpg 768w, https:\/\/blog.panrotas.com.br\/diretodabahia\/wp-content\/uploads\/sites\/4\/2016\/08\/IMG_9993-1024x768.jpg 1024w, https:\/\/blog.panrotas.com.br\/diretodabahia\/wp-content\/uploads\/sites\/4\/2016\/08\/IMG_9993-1568x1176.jpg 1568w\" sizes=\"(max-width: 1632px) 100vw, 1632px\" \/><\/p>\n<p><img loading=\"lazy\" class=\"aligncenter size-full wp-image-136\" src=\"http:\/\/panrotas.blog.br\/diretodabahia\/wp-content\/uploads\/sites\/4\/2016\/08\/IMG_2172.jpg\" alt=\"IMG_2172\" width=\"1024\" height=\"768\" srcset=\"https:\/\/blog.panrotas.com.br\/diretodabahia\/wp-content\/uploads\/sites\/4\/2016\/08\/IMG_2172.jpg 1024w, https:\/\/blog.panrotas.com.br\/diretodabahia\/wp-content\/uploads\/sites\/4\/2016\/08\/IMG_2172-300x225.jpg 300w, https:\/\/blog.panrotas.com.br\/diretodabahia\/wp-content\/uploads\/sites\/4\/2016\/08\/IMG_2172-768x576.jpg 768w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/p>\n<p><img loading=\"lazy\" class=\"aligncenter size-full wp-image-137\" src=\"http:\/\/panrotas.blog.br\/diretodabahia\/wp-content\/uploads\/sites\/4\/2016\/08\/IMG_2202.jpg\" alt=\"IMG_2202\" width=\"1024\" height=\"768\" srcset=\"https:\/\/blog.panrotas.com.br\/diretodabahia\/wp-content\/uploads\/sites\/4\/2016\/08\/IMG_2202.jpg 1024w, https:\/\/blog.panrotas.com.br\/diretodabahia\/wp-content\/uploads\/sites\/4\/2016\/08\/IMG_2202-300x225.jpg 300w, https:\/\/blog.panrotas.com.br\/diretodabahia\/wp-content\/uploads\/sites\/4\/2016\/08\/IMG_2202-768x576.jpg 768w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/p>\n<p>A maior representa\u00e7\u00e3o da nova era chocolat\u00edstica ilheense \u00e9 o Festival Internacional do Chocolate e Cacau, que entrou em sua 8\u00aa edi\u00e7\u00e3o em 2016 &#8211; e literalmente transforma a cidade na capital brasileira do chocolate.<\/p>\n<p><img loading=\"lazy\" class=\"aligncenter size-full wp-image-138\" src=\"http:\/\/panrotas.blog.br\/diretodabahia\/wp-content\/uploads\/sites\/4\/2016\/08\/IMG_2143.jpg\" alt=\"IMG_2143\" width=\"1024\" height=\"768\" srcset=\"https:\/\/blog.panrotas.com.br\/diretodabahia\/wp-content\/uploads\/sites\/4\/2016\/08\/IMG_2143.jpg 1024w, https:\/\/blog.panrotas.com.br\/diretodabahia\/wp-content\/uploads\/sites\/4\/2016\/08\/IMG_2143-300x225.jpg 300w, https:\/\/blog.panrotas.com.br\/diretodabahia\/wp-content\/uploads\/sites\/4\/2016\/08\/IMG_2143-768x576.jpg 768w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/p>\n<p>Neste ano, o Centro de Conven\u00e7\u00f5es de Ilh\u00e9us recebeu mais de 50 expositores de chocolate, palestras, workshops, cursos e shows. Foram dezenas de milhares de visitantes e uma programa\u00e7\u00e3o variada que come\u00e7ava sempre ao final da tarde \u2013 permitindo que turistas fizessem passeios pela regi\u00e3o durante o dia e curtissem o Festival \u00e0 noite.<\/p>\n<p><img loading=\"lazy\" class=\"aligncenter size-full wp-image-139\" src=\"http:\/\/panrotas.blog.br\/diretodabahia\/wp-content\/uploads\/sites\/4\/2016\/08\/IMG_7432.jpg\" alt=\"IMG_7432\" width=\"2448\" height=\"3264\" srcset=\"https:\/\/blog.panrotas.com.br\/diretodabahia\/wp-content\/uploads\/sites\/4\/2016\/08\/IMG_7432.jpg 2448w, https:\/\/blog.panrotas.com.br\/diretodabahia\/wp-content\/uploads\/sites\/4\/2016\/08\/IMG_7432-225x300.jpg 225w, https:\/\/blog.panrotas.com.br\/diretodabahia\/wp-content\/uploads\/sites\/4\/2016\/08\/IMG_7432-768x1024.jpg 768w, https:\/\/blog.panrotas.com.br\/diretodabahia\/wp-content\/uploads\/sites\/4\/2016\/08\/IMG_7432-1568x2091.jpg 1568w\" sizes=\"(max-width: 2448px) 100vw, 2448px\" \/><\/p>\n<p><img loading=\"lazy\" class=\"aligncenter size-full wp-image-140\" src=\"http:\/\/panrotas.blog.br\/diretodabahia\/wp-content\/uploads\/sites\/4\/2016\/08\/IMG_2180.jpg\" alt=\"IMG_2180\" width=\"1024\" height=\"768\" srcset=\"https:\/\/blog.panrotas.com.br\/diretodabahia\/wp-content\/uploads\/sites\/4\/2016\/08\/IMG_2180.jpg 1024w, https:\/\/blog.panrotas.com.br\/diretodabahia\/wp-content\/uploads\/sites\/4\/2016\/08\/IMG_2180-300x225.jpg 300w, https:\/\/blog.panrotas.com.br\/diretodabahia\/wp-content\/uploads\/sites\/4\/2016\/08\/IMG_2180-768x576.jpg 768w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/p>\n<p><img loading=\"lazy\" class=\"aligncenter size-full wp-image-141\" src=\"http:\/\/panrotas.blog.br\/diretodabahia\/wp-content\/uploads\/sites\/4\/2016\/08\/IMG_2411.jpg\" alt=\"IMG_2411\" width=\"1024\" height=\"768\" srcset=\"https:\/\/blog.panrotas.com.br\/diretodabahia\/wp-content\/uploads\/sites\/4\/2016\/08\/IMG_2411.jpg 1024w, https:\/\/blog.panrotas.com.br\/diretodabahia\/wp-content\/uploads\/sites\/4\/2016\/08\/IMG_2411-300x225.jpg 300w, https:\/\/blog.panrotas.com.br\/diretodabahia\/wp-content\/uploads\/sites\/4\/2016\/08\/IMG_2411-768x576.jpg 768w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/p>\n<p><img loading=\"lazy\" class=\"aligncenter size-full wp-image-142\" src=\"http:\/\/panrotas.blog.br\/diretodabahia\/wp-content\/uploads\/sites\/4\/2016\/08\/IMG_2153.jpg\" alt=\"IMG_2153\" width=\"1024\" height=\"768\" srcset=\"https:\/\/blog.panrotas.com.br\/diretodabahia\/wp-content\/uploads\/sites\/4\/2016\/08\/IMG_2153.jpg 1024w, https:\/\/blog.panrotas.com.br\/diretodabahia\/wp-content\/uploads\/sites\/4\/2016\/08\/IMG_2153-300x225.jpg 300w, https:\/\/blog.panrotas.com.br\/diretodabahia\/wp-content\/uploads\/sites\/4\/2016\/08\/IMG_2153-768x576.jpg 768w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/p>\n<p><img loading=\"lazy\" class=\"aligncenter size-full wp-image-143\" src=\"http:\/\/panrotas.blog.br\/diretodabahia\/wp-content\/uploads\/sites\/4\/2016\/08\/IMG_2160.jpg\" alt=\"IMG_2160\" width=\"1024\" height=\"768\" srcset=\"https:\/\/blog.panrotas.com.br\/diretodabahia\/wp-content\/uploads\/sites\/4\/2016\/08\/IMG_2160.jpg 1024w, https:\/\/blog.panrotas.com.br\/diretodabahia\/wp-content\/uploads\/sites\/4\/2016\/08\/IMG_2160-300x225.jpg 300w, https:\/\/blog.panrotas.com.br\/diretodabahia\/wp-content\/uploads\/sites\/4\/2016\/08\/IMG_2160-768x576.jpg 768w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/p>\n<p><img loading=\"lazy\" class=\"aligncenter size-full wp-image-144\" src=\"http:\/\/panrotas.blog.br\/diretodabahia\/wp-content\/uploads\/sites\/4\/2016\/08\/IMG_2163.jpg\" alt=\"IMG_2163\" width=\"1024\" height=\"768\" srcset=\"https:\/\/blog.panrotas.com.br\/diretodabahia\/wp-content\/uploads\/sites\/4\/2016\/08\/IMG_2163.jpg 1024w, https:\/\/blog.panrotas.com.br\/diretodabahia\/wp-content\/uploads\/sites\/4\/2016\/08\/IMG_2163-300x225.jpg 300w, https:\/\/blog.panrotas.com.br\/diretodabahia\/wp-content\/uploads\/sites\/4\/2016\/08\/IMG_2163-768x576.jpg 768w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/p>\n<p><img loading=\"lazy\" class=\"aligncenter size-full wp-image-145\" src=\"http:\/\/panrotas.blog.br\/diretodabahia\/wp-content\/uploads\/sites\/4\/2016\/08\/IMG_2166.jpg\" alt=\"IMG_2166\" width=\"1024\" height=\"768\" srcset=\"https:\/\/blog.panrotas.com.br\/diretodabahia\/wp-content\/uploads\/sites\/4\/2016\/08\/IMG_2166.jpg 1024w, https:\/\/blog.panrotas.com.br\/diretodabahia\/wp-content\/uploads\/sites\/4\/2016\/08\/IMG_2166-300x225.jpg 300w, https:\/\/blog.panrotas.com.br\/diretodabahia\/wp-content\/uploads\/sites\/4\/2016\/08\/IMG_2166-768x576.jpg 768w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/p>\n<p><img loading=\"lazy\" class=\"aligncenter size-full wp-image-146\" src=\"http:\/\/panrotas.blog.br\/diretodabahia\/wp-content\/uploads\/sites\/4\/2016\/08\/IMG_2169.jpg\" alt=\"IMG_2169\" width=\"1024\" height=\"768\" srcset=\"https:\/\/blog.panrotas.com.br\/diretodabahia\/wp-content\/uploads\/sites\/4\/2016\/08\/IMG_2169.jpg 1024w, https:\/\/blog.panrotas.com.br\/diretodabahia\/wp-content\/uploads\/sites\/4\/2016\/08\/IMG_2169-300x225.jpg 300w, https:\/\/blog.panrotas.com.br\/diretodabahia\/wp-content\/uploads\/sites\/4\/2016\/08\/IMG_2169-768x576.jpg 768w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/p>\n<p>Fora do Centro de Conven\u00e7\u00f5es, a cidade tamb\u00e9m entrava na onda chocolateira: na Pousada Morro dos Navegantes, por exemplo, rolou at\u00e9 o jantar tem\u00e1tico \u2018Trilogia do Chocolate\u2019, com o apoio da marca Chor.<\/p>\n<p><img loading=\"lazy\" class=\"aligncenter size-full wp-image-147\" src=\"http:\/\/panrotas.blog.br\/diretodabahia\/wp-content\/uploads\/sites\/4\/2016\/08\/IMG_7368.jpg\" alt=\"IMG_7368\" width=\"1632\" height=\"1224\" srcset=\"https:\/\/blog.panrotas.com.br\/diretodabahia\/wp-content\/uploads\/sites\/4\/2016\/08\/IMG_7368.jpg 1632w, https:\/\/blog.panrotas.com.br\/diretodabahia\/wp-content\/uploads\/sites\/4\/2016\/08\/IMG_7368-300x225.jpg 300w, https:\/\/blog.panrotas.com.br\/diretodabahia\/wp-content\/uploads\/sites\/4\/2016\/08\/IMG_7368-768x576.jpg 768w, https:\/\/blog.panrotas.com.br\/diretodabahia\/wp-content\/uploads\/sites\/4\/2016\/08\/IMG_7368-1024x768.jpg 1024w, https:\/\/blog.panrotas.com.br\/diretodabahia\/wp-content\/uploads\/sites\/4\/2016\/08\/IMG_7368-1568x1176.jpg 1568w\" sizes=\"(max-width: 1632px) 100vw, 1632px\" \/><\/p>\n<p>Al\u00e9m do City Tour e das visitas \u00e0s fazendas, fomos conhecer a f\u00e1brica de chocolates da Mendo\u00e1, e tivemos um tour guiado por todas as instala\u00e7\u00f5es. Nem sinal de Willy Wonka, oompa loompas e cascata de chocolate \u2013 era tudo na concentra\u00e7\u00e3o, seriedade e essa roupa de filme de fic\u00e7\u00e3o cient\u00edfica.<\/p>\n<p><img loading=\"lazy\" class=\"aligncenter size-full wp-image-148\" src=\"http:\/\/panrotas.blog.br\/diretodabahia\/wp-content\/uploads\/sites\/4\/2016\/08\/IMG_2337.jpg\" alt=\"IMG_2337\" width=\"1024\" height=\"768\" srcset=\"https:\/\/blog.panrotas.com.br\/diretodabahia\/wp-content\/uploads\/sites\/4\/2016\/08\/IMG_2337.jpg 1024w, https:\/\/blog.panrotas.com.br\/diretodabahia\/wp-content\/uploads\/sites\/4\/2016\/08\/IMG_2337-300x225.jpg 300w, https:\/\/blog.panrotas.com.br\/diretodabahia\/wp-content\/uploads\/sites\/4\/2016\/08\/IMG_2337-768x576.jpg 768w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/p>\n<p>A forma mais f\u00e1cil para quem visita a cidade fora do Festival, e quer encontrar a maioria desses chocolates, \u00e9 dar uma passadinha na loja multimarcas que funciona no Bataclan, um dos principais pontos tur\u00edsticos de Ilh\u00e9us.<\/p>\n<p><img loading=\"lazy\" class=\"aligncenter size-full wp-image-149\" src=\"http:\/\/panrotas.blog.br\/diretodabahia\/wp-content\/uploads\/sites\/4\/2016\/08\/IMG_2115.jpg\" alt=\"IMG_2115\" width=\"1024\" height=\"768\" srcset=\"https:\/\/blog.panrotas.com.br\/diretodabahia\/wp-content\/uploads\/sites\/4\/2016\/08\/IMG_2115.jpg 1024w, https:\/\/blog.panrotas.com.br\/diretodabahia\/wp-content\/uploads\/sites\/4\/2016\/08\/IMG_2115-300x225.jpg 300w, https:\/\/blog.panrotas.com.br\/diretodabahia\/wp-content\/uploads\/sites\/4\/2016\/08\/IMG_2115-768x576.jpg 768w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/p>\n<p>PROGRAME-SE: a pr\u00f3xima edi\u00e7\u00e3o do Festival Internacional do Chocolate ocorrer\u00e1 de 20 a 23 de julho de 2017. Mais informa\u00e7\u00f5es no site: <a href=\"http:\/\/www.festivaldochocolate.com\">www.festivaldochocolate.com<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>As primeiras sementes de cacau chegaram na Bahia em meados do s\u00e9culo XVIII. Trazidas diretamente da Amaz\u00f4nia, o fruto encontrou na Mata Atl\u00e2ntica um ambiente ideal para o seu desenvolvimento. Por aqui, o sistema de cultivo ganhou o nome de \u201ccabruca\u201d, no qual os p\u00e9s de cacau s\u00e3o plantados dentro da mata j\u00e1 existente, garantindo&hellip; <a class=\"more-link\" href=\"https:\/\/blog.panrotas.com.br\/diretodabahia\/2016\/08\/13\/a-reinvencao-do-chocolate-e-de-uma-cidade-inteira\/\">Continue reading &rarr;<\/a><\/p>\n","protected":false},"author":8,"featured_media":150,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[1],"tags":[],"_links":{"self":[{"href":"https:\/\/blog.panrotas.com.br\/diretodabahia\/wp-json\/wp\/v2\/posts\/118"}],"collection":[{"href":"https:\/\/blog.panrotas.com.br\/diretodabahia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.panrotas.com.br\/diretodabahia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog.panrotas.com.br\/diretodabahia\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.panrotas.com.br\/diretodabahia\/wp-json\/wp\/v2\/comments?post=118"}],"version-history":[{"count":1,"href":"https:\/\/blog.panrotas.com.br\/diretodabahia\/wp-json\/wp\/v2\/posts\/118\/revisions"}],"predecessor-version":[{"id":586,"href":"https:\/\/blog.panrotas.com.br\/diretodabahia\/wp-json\/wp\/v2\/posts\/118\/revisions\/586"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blog.panrotas.com.br\/diretodabahia\/wp-json\/wp\/v2\/media\/150"}],"wp:attachment":[{"href":"https:\/\/blog.panrotas.com.br\/diretodabahia\/wp-json\/wp\/v2\/media?parent=118"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.panrotas.com.br\/diretodabahia\/wp-json\/wp\/v2\/categories?post=118"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.panrotas.com.br\/diretodabahia\/wp-json\/wp\/v2\/tags?post=118"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}