{"id":459,"date":"2017-04-04T16:22:38","date_gmt":"2017-04-04T19:22:38","guid":{"rendered":"http:\/\/blog.panrotas.com.br\/diretodabahia\/?p=459"},"modified":"2019-05-17T17:53:23","modified_gmt":"2019-05-17T20:53:23","slug":"sheraton-da-bahia-investe-em-pacotes-com-ingressos-para-a-concha-acustica","status":"publish","type":"post","link":"https:\/\/blog.panrotas.com.br\/diretodabahia\/2017\/04\/04\/sheraton-da-bahia-investe-em-pacotes-com-ingressos-para-a-concha-acustica\/","title":{"rendered":"Sheraton da Bahia investe em pacotes com ingressos para a Concha Ac\u00fastica"},"content":{"rendered":"<p>Desde a reinaugura\u00e7\u00e3o da Concha Ac\u00fastica, um dos mais famosos espa\u00e7os culturais de Salvador, o Hotel Sheraton da Bahia vem lan\u00e7ando pacotes especiais para clientes que desejem combinar uma boa hospedagem com uma das op\u00e7\u00f5es da variada programa\u00e7\u00e3o do local.<\/p>\n<p>Somente no 2\u00ba Semestre de 2016, a Concha Ac\u00fastica recebeu apresenta\u00e7\u00f5es de nomes de peso como Maria Bethania, Djavan, Lulu Santos, Criolo, Paralamas do Sucesso, Zeca Pagodinho, Nando Reis, Beth Carvalho, Z\u00e9 Ramalho, A Cor do Som, Emicida e Teatro M\u00e1gico. Em 2017, j\u00e1 abriu os trabalhos com Caetano Veloso, Novos Baianos, Carlinhos Brown, Vanessa da Mata, Liniker e os Caramelows, Gilberto Gil e os Filhos de Gandhy. De longe, a mais soteropolitana das casas de espet\u00e1culos.<\/p>\n<p>E n\u00e3o apenas isso: fazendo parte de uma estrutura muito mais grandiosa \u2013 o Complexo Cultural do Teatro Castro Alves \u2013 a Concha \u00e9 apenas uma pe\u00e7a de uma imensa engrenagem que movimenta a cena cultural de Salvador, envolvendo ainda uma orquestra sinf\u00f4nica (a OSBA), uma cia de dan\u00e7a (o BTCA) e diversos espa\u00e7os com agenda ininterrupta de eventos \u2013 a Sala do Coro, a Sala Principal, as Salas de Ensaio, o Foyer, o V\u00e3o Livre e a pr\u00f3pria Concha.<\/p>\n<p>O Sheraton juntou 2 + 2, fez a li\u00e7\u00e3o de casa, e aproveitando a excelente localiza\u00e7\u00e3o, no Campo Grande \u2013 o hotel e a Concha est\u00e3o separados apenas por uma pra\u00e7a \u2013, vem lan\u00e7ando uma s\u00e9rie de promo\u00e7\u00f5es que incluem um par de convites para o show e comodidades como late check out (mediante disponibilidade) e cortesia de estacionamento.<\/p>\n<p>Para o m\u00eas de abril, o hotel j\u00e1 divulgou os pacotes para os shows de Roupa Nova (08\/04) e do Grande Encontro, com Elba Ramalho, Geraldo Azevedo e Alceu Valen\u00e7a (22\/04), no valor de R$290 a di\u00e1ria (mais impostos). Se comprados separadamente, apenas os ingressos n\u00e3o sairiam por menos de R$200, e isso sem mencionar os gastos com transporte, flanelinha e derivados.<\/p>\n<p>Foi um prato cheio para o p\u00fablico soteropolitano, com a oportunidade de se hospedar num dos hot\u00e9is mais desejados da cidade e curtir o show sem a preocupa\u00e7\u00e3o com estacionamento e a volta para casa.<\/p>\n<p>RESERVAS<\/p>\n<p>Telefone: (71) 3021-6700<\/p>\n<p>E-mail: <a href=\"mailto:reservas@sheratondabahia.com\">reservas@sheratondabahia.com<\/a><\/p>\n<p>*As promo\u00e7\u00f5es n\u00e3o est\u00e3o dispon\u00edveis em canais on line; reservas somente com a central de reservas do hotel<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Desde a reinaugura\u00e7\u00e3o da Concha Ac\u00fastica, um dos mais famosos espa\u00e7os culturais de Salvador, o Hotel Sheraton da Bahia vem lan\u00e7ando pacotes especiais para clientes que desejem combinar uma boa hospedagem com uma das op\u00e7\u00f5es da variada programa\u00e7\u00e3o do local. Somente no 2\u00ba Semestre de 2016, a Concha Ac\u00fastica recebeu apresenta\u00e7\u00f5es de nomes de peso&hellip; <a class=\"more-link\" href=\"https:\/\/blog.panrotas.com.br\/diretodabahia\/2017\/04\/04\/sheraton-da-bahia-investe-em-pacotes-com-ingressos-para-a-concha-acustica\/\">Continue reading &rarr;<\/a><\/p>\n","protected":false},"author":8,"featured_media":462,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"spay_email":"","jetpack_publicize_message":"","jetpack_is_tweetstorm":false},"categories":[1],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v17.3 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Sheraton da Bahia investe em pacotes com ingressos para a Concha Ac\u00fastica - Direto da Bahia<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/blog.panrotas.com.br\/diretodabahia\/2017\/04\/04\/sheraton-da-bahia-investe-em-pacotes-com-ingressos-para-a-concha-acustica\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Sheraton da Bahia investe em pacotes com ingressos para a Concha Ac\u00fastica - Direto da Bahia\" \/>\n<meta property=\"og:description\" content=\"Desde a reinaugura\u00e7\u00e3o da Concha Ac\u00fastica, um dos mais famosos espa\u00e7os culturais de Salvador, o Hotel Sheraton da Bahia vem lan\u00e7ando pacotes especiais para clientes que desejem combinar uma boa hospedagem com uma das op\u00e7\u00f5es da variada programa\u00e7\u00e3o do local. Somente no 2\u00ba Semestre de 2016, a Concha Ac\u00fastica recebeu apresenta\u00e7\u00f5es de nomes de peso&hellip; Continue reading &rarr;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/blog.panrotas.com.br\/diretodabahia\/2017\/04\/04\/sheraton-da-bahia-investe-em-pacotes-com-ingressos-para-a-concha-acustica\/\" \/>\n<meta property=\"og:site_name\" content=\"Direto da Bahia\" \/>\n<meta property=\"article:published_time\" content=\"2017-04-04T19:22:38+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-05-17T20:53:23+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/blog.panrotas.com.br\/diretodabahia\/wp-content\/uploads\/sites\/4\/2017\/04\/09062015103909-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1108\" \/>\n\t<meta property=\"og:image:height\" content=\"419\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Iuri Barreto\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/blog.panrotas.com.br\/diretodabahia\/#website\",\"url\":\"https:\/\/blog.panrotas.com.br\/diretodabahia\/\",\"name\":\"Direto da Bahia\",\"description\":\"Blogosfera PANROTAS\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/blog.panrotas.com.br\/diretodabahia\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/blog.panrotas.com.br\/diretodabahia\/2017\/04\/04\/sheraton-da-bahia-investe-em-pacotes-com-ingressos-para-a-concha-acustica\/#primaryimage\",\"inLanguage\":\"pt-BR\",\"url\":\"https:\/\/blog.panrotas.com.br\/diretodabahia\/wp-content\/uploads\/sites\/4\/2017\/04\/09062015103909-1.jpg\",\"contentUrl\":\"https:\/\/blog.panrotas.com.br\/diretodabahia\/wp-content\/uploads\/sites\/4\/2017\/04\/09062015103909-1.jpg\",\"width\":1108,\"height\":419},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/blog.panrotas.com.br\/diretodabahia\/2017\/04\/04\/sheraton-da-bahia-investe-em-pacotes-com-ingressos-para-a-concha-acustica\/#webpage\",\"url\":\"https:\/\/blog.panrotas.com.br\/diretodabahia\/2017\/04\/04\/sheraton-da-bahia-investe-em-pacotes-com-ingressos-para-a-concha-acustica\/\",\"name\":\"Sheraton da Bahia investe em pacotes com ingressos para a Concha Ac\\u00fastica - Direto da Bahia\",\"isPartOf\":{\"@id\":\"https:\/\/blog.panrotas.com.br\/diretodabahia\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/blog.panrotas.com.br\/diretodabahia\/2017\/04\/04\/sheraton-da-bahia-investe-em-pacotes-com-ingressos-para-a-concha-acustica\/#primaryimage\"},\"datePublished\":\"2017-04-04T19:22:38+00:00\",\"dateModified\":\"2019-05-17T20:53:23+00:00\",\"author\":{\"@id\":\"https:\/\/blog.panrotas.com.br\/diretodabahia\/#\/schema\/person\/22ff06ac6bcffa57fab248d7b4fa2cd4\"},\"breadcrumb\":{\"@id\":\"https:\/\/blog.panrotas.com.br\/diretodabahia\/2017\/04\/04\/sheraton-da-bahia-investe-em-pacotes-com-ingressos-para-a-concha-acustica\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/blog.panrotas.com.br\/diretodabahia\/2017\/04\/04\/sheraton-da-bahia-investe-em-pacotes-com-ingressos-para-a-concha-acustica\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/blog.panrotas.com.br\/diretodabahia\/2017\/04\/04\/sheraton-da-bahia-investe-em-pacotes-com-ingressos-para-a-concha-acustica\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\\u00edcio\",\"item\":\"https:\/\/blog.panrotas.com.br\/diretodabahia\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Sheraton da Bahia investe em pacotes com ingressos para a Concha Ac\\u00fastica\"}]},{\"@type\":\"Person\",\"@id\":\"https:\/\/blog.panrotas.com.br\/diretodabahia\/#\/schema\/person\/22ff06ac6bcffa57fab248d7b4fa2cd4\",\"name\":\"Iuri Barreto\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/blog.panrotas.com.br\/diretodabahia\/#personlogo\",\"inLanguage\":\"pt-BR\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/7411c692ffbd1927ab46ae587d558382?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/7411c692ffbd1927ab46ae587d558382?s=96&d=mm&r=g\",\"caption\":\"Iuri Barreto\"},\"description\":\"Iuri Barreto \\u00e9 formado em Direito pela Universidade Federal da Bahia e Gerente de Comunica\\u00e7\\u00e3o da Grou Turismo. \\u00c9 baiano de alma, nascimento e profiss\\u00e3o, e tamb\\u00e9m o autor do Guia do Soteropobretano, blog com mais de 130 mil seguidores nas redes sociais.\",\"sameAs\":[\"http:\/\/www.grou.com.br\"],\"url\":\"https:\/\/blog.panrotas.com.br\/diretodabahia\/author\/iuri\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Sheraton da Bahia investe em pacotes com ingressos para a Concha Ac\u00fastica - Direto da Bahia","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/blog.panrotas.com.br\/diretodabahia\/2017\/04\/04\/sheraton-da-bahia-investe-em-pacotes-com-ingressos-para-a-concha-acustica\/","og_locale":"pt_BR","og_type":"article","og_title":"Sheraton da Bahia investe em pacotes com ingressos para a Concha Ac\u00fastica - Direto da Bahia","og_description":"Desde a reinaugura\u00e7\u00e3o da Concha Ac\u00fastica, um dos mais famosos espa\u00e7os culturais de Salvador, o Hotel Sheraton da Bahia vem lan\u00e7ando pacotes especiais para clientes que desejem combinar uma boa hospedagem com uma das op\u00e7\u00f5es da variada programa\u00e7\u00e3o do local. Somente no 2\u00ba Semestre de 2016, a Concha Ac\u00fastica recebeu apresenta\u00e7\u00f5es de nomes de peso&hellip; Continue reading &rarr;","og_url":"https:\/\/blog.panrotas.com.br\/diretodabahia\/2017\/04\/04\/sheraton-da-bahia-investe-em-pacotes-com-ingressos-para-a-concha-acustica\/","og_site_name":"Direto da Bahia","article_published_time":"2017-04-04T19:22:38+00:00","article_modified_time":"2019-05-17T20:53:23+00:00","og_image":[{"width":1108,"height":419,"url":"https:\/\/blog.panrotas.com.br\/diretodabahia\/wp-content\/uploads\/sites\/4\/2017\/04\/09062015103909-1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Iuri Barreto","Est. tempo de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebSite","@id":"https:\/\/blog.panrotas.com.br\/diretodabahia\/#website","url":"https:\/\/blog.panrotas.com.br\/diretodabahia\/","name":"Direto da Bahia","description":"Blogosfera PANROTAS","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/blog.panrotas.com.br\/diretodabahia\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"pt-BR"},{"@type":"ImageObject","@id":"https:\/\/blog.panrotas.com.br\/diretodabahia\/2017\/04\/04\/sheraton-da-bahia-investe-em-pacotes-com-ingressos-para-a-concha-acustica\/#primaryimage","inLanguage":"pt-BR","url":"https:\/\/blog.panrotas.com.br\/diretodabahia\/wp-content\/uploads\/sites\/4\/2017\/04\/09062015103909-1.jpg","contentUrl":"https:\/\/blog.panrotas.com.br\/diretodabahia\/wp-content\/uploads\/sites\/4\/2017\/04\/09062015103909-1.jpg","width":1108,"height":419},{"@type":"WebPage","@id":"https:\/\/blog.panrotas.com.br\/diretodabahia\/2017\/04\/04\/sheraton-da-bahia-investe-em-pacotes-com-ingressos-para-a-concha-acustica\/#webpage","url":"https:\/\/blog.panrotas.com.br\/diretodabahia\/2017\/04\/04\/sheraton-da-bahia-investe-em-pacotes-com-ingressos-para-a-concha-acustica\/","name":"Sheraton da Bahia investe em pacotes com ingressos para a Concha Ac\u00fastica - Direto da Bahia","isPartOf":{"@id":"https:\/\/blog.panrotas.com.br\/diretodabahia\/#website"},"primaryImageOfPage":{"@id":"https:\/\/blog.panrotas.com.br\/diretodabahia\/2017\/04\/04\/sheraton-da-bahia-investe-em-pacotes-com-ingressos-para-a-concha-acustica\/#primaryimage"},"datePublished":"2017-04-04T19:22:38+00:00","dateModified":"2019-05-17T20:53:23+00:00","author":{"@id":"https:\/\/blog.panrotas.com.br\/diretodabahia\/#\/schema\/person\/22ff06ac6bcffa57fab248d7b4fa2cd4"},"breadcrumb":{"@id":"https:\/\/blog.panrotas.com.br\/diretodabahia\/2017\/04\/04\/sheraton-da-bahia-investe-em-pacotes-com-ingressos-para-a-concha-acustica\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/blog.panrotas.com.br\/diretodabahia\/2017\/04\/04\/sheraton-da-bahia-investe-em-pacotes-com-ingressos-para-a-concha-acustica\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/blog.panrotas.com.br\/diretodabahia\/2017\/04\/04\/sheraton-da-bahia-investe-em-pacotes-com-ingressos-para-a-concha-acustica\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/blog.panrotas.com.br\/diretodabahia\/"},{"@type":"ListItem","position":2,"name":"Sheraton da Bahia investe em pacotes com ingressos para a Concha Ac\u00fastica"}]},{"@type":"Person","@id":"https:\/\/blog.panrotas.com.br\/diretodabahia\/#\/schema\/person\/22ff06ac6bcffa57fab248d7b4fa2cd4","name":"Iuri Barreto","image":{"@type":"ImageObject","@id":"https:\/\/blog.panrotas.com.br\/diretodabahia\/#personlogo","inLanguage":"pt-BR","url":"https:\/\/secure.gravatar.com\/avatar\/7411c692ffbd1927ab46ae587d558382?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/7411c692ffbd1927ab46ae587d558382?s=96&d=mm&r=g","caption":"Iuri Barreto"},"description":"Iuri Barreto \u00e9 formado em Direito pela Universidade Federal da Bahia e Gerente de Comunica\u00e7\u00e3o da Grou Turismo. \u00c9 baiano de alma, nascimento e profiss\u00e3o, e tamb\u00e9m o autor do Guia do Soteropobretano, blog com mais de 130 mil seguidores nas redes sociais.","sameAs":["http:\/\/www.grou.com.br"],"url":"https:\/\/blog.panrotas.com.br\/diretodabahia\/author\/iuri\/"}]}},"jetpack_featured_media_url":"https:\/\/blog.panrotas.com.br\/diretodabahia\/wp-content\/uploads\/sites\/4\/2017\/04\/09062015103909-1.jpg","jetpack_publicize_connections":[],"jetpack_shortlink":"https:\/\/wp.me\/p7CH4N-7p","_links":{"self":[{"href":"https:\/\/blog.panrotas.com.br\/diretodabahia\/wp-json\/wp\/v2\/posts\/459"}],"collection":[{"href":"https:\/\/blog.panrotas.com.br\/diretodabahia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.panrotas.com.br\/diretodabahia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog.panrotas.com.br\/diretodabahia\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.panrotas.com.br\/diretodabahia\/wp-json\/wp\/v2\/comments?post=459"}],"version-history":[{"count":1,"href":"https:\/\/blog.panrotas.com.br\/diretodabahia\/wp-json\/wp\/v2\/posts\/459\/revisions"}],"predecessor-version":[{"id":570,"href":"https:\/\/blog.panrotas.com.br\/diretodabahia\/wp-json\/wp\/v2\/posts\/459\/revisions\/570"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blog.panrotas.com.br\/diretodabahia\/wp-json\/wp\/v2\/media\/462"}],"wp:attachment":[{"href":"https:\/\/blog.panrotas.com.br\/diretodabahia\/wp-json\/wp\/v2\/media?parent=459"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.panrotas.com.br\/diretodabahia\/wp-json\/wp\/v2\/categories?post=459"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.panrotas.com.br\/diretodabahia\/wp-json\/wp\/v2\/tags?post=459"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}