{"id":465,"date":"2017-04-11T18:19:48","date_gmt":"2017-04-11T21:19:48","guid":{"rendered":"http:\/\/blog.panrotas.com.br\/diretodabahia\/?p=465"},"modified":"2019-05-17T17:54:20","modified_gmt":"2019-05-17T20:54:20","slug":"itacare-um-destino-completo-e-em-constante-aprendizado","status":"publish","type":"post","link":"https:\/\/blog.panrotas.com.br\/diretodabahia\/2017\/04\/11\/itacare-um-destino-completo-e-em-constante-aprendizado\/","title":{"rendered":"Itacar\u00e9: um destino completo \u2013 e em constante aprendizado"},"content":{"rendered":"<p><em>Que o Brasil tem belas e maravilhosas praias, ningu\u00e9m duvida. Mas algumas delas possuem, indiscutivelmente, algo de muito especial que termina por coloc\u00e1-las numa esp\u00e9cie de Olimpo praieiro muito particular. Itacar\u00e9, a nova queridinha do litoral baiano, \u00e9 a mais recente a entrar nesse rol das praias mais badaladas do Pa\u00eds. E, acreditem, muita gente n\u00e3o est\u00e1 muito feliz com essa fama, especialmente as dezenas de famosos e VIPs que procuram uma das 16 prainhas locais para relaxar e fugir dos f\u00e3s. O tenista Gustavo Kuerten, a apresentadora Babi e seu indefect\u00edvel Marcos Mion, al\u00e9m de medalh\u00f5es como Jos\u00e9 Roberto Marinho (que est\u00e1 construindo uma luxuosa mans\u00e3o no local) s\u00e3o alguns desses nomes que dariam tudo para manter Itacar\u00e9 no limbo. Mas agora \u00e9 tarde.<br \/>\n<\/em><br \/>\nO trecho acima foi retirado de uma mat\u00e9ria de 2002, no Jornal do Commercio (Pernambuco). Naquela \u00e9poca, nos primeiros anos depois que o destino caiu nas gra\u00e7as do mundo, o dif\u00edcil era abrir uma p\u00e1gina da Revista CARAS e n\u00e3o encontrar alguma celebridade se dizendo apaixonada por Itacar\u00e9. J\u00e1 teve Nicolas Sarkozy e Carla Bruni, Keanu Reeves e Orlando Bloom, e isso para n\u00e3o falar dos famosos nacionais que desembarcavam por l\u00e1 aos montes. Teve at\u00e9 lista no The New York Times, em 2007, ocasi\u00e3o em que Itacar\u00e9 apareceu como um dos \u201950 Lugares do Mundo para Visitar\u2019.<\/p>\n<p>Volte ao par\u00e1grafo que abre esse texto. Leia novamente. Destaque o trecho \u201c&#8230;muita gente n\u00e3o est\u00e1 muito feliz com essa fama\u201d e \u201c&#8230;dariam tudo para manter Itacar\u00e9 no limbo. Mas agora \u00e9 tarde\u201d.<\/p>\n<p>Quinze anos depois, o destino n\u00e3o \u00e9 mais o mesmo. Das p\u00e1ginas das revistas de celebridades e dos sonhos de in\u00fameros viajantes, Itacar\u00e9 foi perdendo visibilidade e se transformou numa vaga lembran\u00e7a para muita gente. Um nome familiar que raramente surge na conversa entre o cliente e o agente de viagens. As praias continuam bel\u00edssimas e semi-desertas, as trilhas continuam espetaculares e h\u00e1 pousadas e hot\u00e9is com tarifas para todos os bolsos. Mas no processo de amadurecimento do destino, algo se perdeu.<\/p>\n<p>Digo sempre que em lugar de buscar culpados, devemos aprender com os erros e omiss\u00f5es. Problemas ambientais, relatos de inseguran\u00e7a e um crescimento pouco sustent\u00e1vel foram algumas das raz\u00f5es que contribu\u00edram para a perda de competitividade, mas a boa not\u00edcia \u00e9 que o destino ainda encanta aos visitantes e surpreende positivamente \u2013 talvez pela pouca expectativa com que chegam ao local. Felizmente, j\u00e1 se nota mudan\u00e7as no horizonte: lan\u00e7ada durante a edi\u00e7\u00e3o desse ano da WTM Latin America, em S\u00e3o Paulo, a campanha \u2018Itacar\u00e9 \u2013 Um Destino Completo\u2019 apresentou ao trade um novo conceito, com identidade visual repaginada e um calend\u00e1rio de eventos que, se n\u00e3o chega a ser preponderante para a decis\u00e3o do cliente final, tem grande import\u00e2ncia para o posicionamento do destino no mercado. Al\u00e9m do IV Festival Gastron\u00f4mico Sabores de Itacar\u00e9, antecipado de dezembro para julho, a Semana Santa vai virar praticamente um S\u00e3o Jo\u00e3o fora de \u00e9poca, com o I Festival de Forr\u00f3.<\/p>\n<p>De crian\u00e7a prod\u00edgio no Turismo Baiano, e passando por uma adolesc\u00eancia turbulenta, Itacar\u00e9 chega \u00e0 vida adulta com muito trabalho a ser feito para recuperar o tempo perdido.<\/p>\n<p><img loading=\"lazy\" class=\"aligncenter size-full wp-image-467\" src=\"http:\/\/panrotas.blog.br\/diretodabahia\/wp-content\/uploads\/sites\/4\/2017\/04\/15873565_376093929415215_7899133428185624417_n.jpg\" alt=\"\" width=\"960\" height=\"392\" srcset=\"https:\/\/blog.panrotas.com.br\/diretodabahia\/wp-content\/uploads\/sites\/4\/2017\/04\/15873565_376093929415215_7899133428185624417_n.jpg 960w, https:\/\/blog.panrotas.com.br\/diretodabahia\/wp-content\/uploads\/sites\/4\/2017\/04\/15873565_376093929415215_7899133428185624417_n-300x123.jpg 300w, https:\/\/blog.panrotas.com.br\/diretodabahia\/wp-content\/uploads\/sites\/4\/2017\/04\/15873565_376093929415215_7899133428185624417_n-768x314.jpg 768w\" sizes=\"(max-width: 960px) 100vw, 960px\" \/><img loading=\"lazy\" class=\"aligncenter size-full wp-image-468\" src=\"http:\/\/panrotas.blog.br\/diretodabahia\/wp-content\/uploads\/sites\/4\/2017\/04\/IMG_9197.jpg\" alt=\"\" width=\"2048\" height=\"1449\" srcset=\"https:\/\/blog.panrotas.com.br\/diretodabahia\/wp-content\/uploads\/sites\/4\/2017\/04\/IMG_9197.jpg 2048w, https:\/\/blog.panrotas.com.br\/diretodabahia\/wp-content\/uploads\/sites\/4\/2017\/04\/IMG_9197-300x212.jpg 300w, https:\/\/blog.panrotas.com.br\/diretodabahia\/wp-content\/uploads\/sites\/4\/2017\/04\/IMG_9197-768x543.jpg 768w, https:\/\/blog.panrotas.com.br\/diretodabahia\/wp-content\/uploads\/sites\/4\/2017\/04\/IMG_9197-1024x725.jpg 1024w, https:\/\/blog.panrotas.com.br\/diretodabahia\/wp-content\/uploads\/sites\/4\/2017\/04\/IMG_9197-1568x1109.jpg 1568w\" sizes=\"(max-width: 2048px) 100vw, 2048px\" \/><img loading=\"lazy\" class=\"aligncenter size-full wp-image-469\" src=\"http:\/\/panrotas.blog.br\/diretodabahia\/wp-content\/uploads\/sites\/4\/2017\/04\/17353310_1891441020873330_4367334606418897252_n.jpg\" alt=\"\" width=\"960\" height=\"368\" srcset=\"https:\/\/blog.panrotas.com.br\/diretodabahia\/wp-content\/uploads\/sites\/4\/2017\/04\/17353310_1891441020873330_4367334606418897252_n.jpg 960w, https:\/\/blog.panrotas.com.br\/diretodabahia\/wp-content\/uploads\/sites\/4\/2017\/04\/17353310_1891441020873330_4367334606418897252_n-300x115.jpg 300w, https:\/\/blog.panrotas.com.br\/diretodabahia\/wp-content\/uploads\/sites\/4\/2017\/04\/17353310_1891441020873330_4367334606418897252_n-768x294.jpg 768w\" sizes=\"(max-width: 960px) 100vw, 960px\" \/><\/p>\n<figure id=\"attachment_470\" aria-describedby=\"caption-attachment-470\" style=\"width: 1040px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" class=\"wp-image-470 size-full\" src=\"http:\/\/panrotas.blog.br\/diretodabahia\/wp-content\/uploads\/sites\/4\/2017\/04\/IMG_9195.jpg\" alt=\"\" width=\"1040\" height=\"780\" srcset=\"https:\/\/blog.panrotas.com.br\/diretodabahia\/wp-content\/uploads\/sites\/4\/2017\/04\/IMG_9195.jpg 1040w, https:\/\/blog.panrotas.com.br\/diretodabahia\/wp-content\/uploads\/sites\/4\/2017\/04\/IMG_9195-300x225.jpg 300w, https:\/\/blog.panrotas.com.br\/diretodabahia\/wp-content\/uploads\/sites\/4\/2017\/04\/IMG_9195-768x576.jpg 768w, https:\/\/blog.panrotas.com.br\/diretodabahia\/wp-content\/uploads\/sites\/4\/2017\/04\/IMG_9195-1024x768.jpg 1024w\" sizes=\"(max-width: 1040px) 100vw, 1040px\" \/><figcaption id=\"caption-attachment-470\" class=\"wp-caption-text\">Mena Mota (Grou Turismo), J\u00falio Oliveira (Secret\u00e1rio de Turismo de Itacar\u00e9) e Rodrigo Galv\u00e3o (CVC) durante a WTM<\/figcaption><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Que o Brasil tem belas e maravilhosas praias, ningu\u00e9m duvida. Mas algumas delas possuem, indiscutivelmente, algo de muito especial que termina por coloc\u00e1-las numa esp\u00e9cie de Olimpo praieiro muito particular. Itacar\u00e9, a nova queridinha do litoral baiano, \u00e9 a mais recente a entrar nesse rol das praias mais badaladas do Pa\u00eds. E, acreditem, muita gente&hellip; <a class=\"more-link\" href=\"https:\/\/blog.panrotas.com.br\/diretodabahia\/2017\/04\/11\/itacare-um-destino-completo-e-em-constante-aprendizado\/\">Continue reading &rarr;<\/a><\/p>\n","protected":false},"author":8,"featured_media":471,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[1],"tags":[],"_links":{"self":[{"href":"https:\/\/blog.panrotas.com.br\/diretodabahia\/wp-json\/wp\/v2\/posts\/465"}],"collection":[{"href":"https:\/\/blog.panrotas.com.br\/diretodabahia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.panrotas.com.br\/diretodabahia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog.panrotas.com.br\/diretodabahia\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.panrotas.com.br\/diretodabahia\/wp-json\/wp\/v2\/comments?post=465"}],"version-history":[{"count":1,"href":"https:\/\/blog.panrotas.com.br\/diretodabahia\/wp-json\/wp\/v2\/posts\/465\/revisions"}],"predecessor-version":[{"id":569,"href":"https:\/\/blog.panrotas.com.br\/diretodabahia\/wp-json\/wp\/v2\/posts\/465\/revisions\/569"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blog.panrotas.com.br\/diretodabahia\/wp-json\/wp\/v2\/media\/471"}],"wp:attachment":[{"href":"https:\/\/blog.panrotas.com.br\/diretodabahia\/wp-json\/wp\/v2\/media?parent=465"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.panrotas.com.br\/diretodabahia\/wp-json\/wp\/v2\/categories?post=465"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.panrotas.com.br\/diretodabahia\/wp-json\/wp\/v2\/tags?post=465"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}