{"id":3388,"date":"2020-07-23T16:40:16","date_gmt":"2020-07-23T19:40:16","guid":{"rendered":"http:\/\/blog.panrotas.com.br\/mktdestinos\/?p=3388"},"modified":"2020-07-23T16:40:18","modified_gmt":"2020-07-23T19:40:18","slug":"3-papos-imperdiveis","status":"publish","type":"post","link":"https:\/\/blog.panrotas.com.br\/mktdestinos\/2020\/07\/23\/3-papos-imperdiveis\/","title":{"rendered":"3 papos imperd\u00edveis"},"content":{"rendered":"\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" width=\"1024\" height=\"538\" src=\"https:\/\/blog.panrotas.com.br\/mktdestinos\/wp-content\/uploads\/sites\/23\/2020\/07\/2000ouvintes_1_original-1-1024x538.jpg\" alt=\"\" class=\"wp-image-3392\" srcset=\"https:\/\/blog.panrotas.com.br\/mktdestinos\/wp-content\/uploads\/sites\/23\/2020\/07\/2000ouvintes_1_original-1-1024x538.jpg 1024w, https:\/\/blog.panrotas.com.br\/mktdestinos\/wp-content\/uploads\/sites\/23\/2020\/07\/2000ouvintes_1_original-1-300x158.jpg 300w, https:\/\/blog.panrotas.com.br\/mktdestinos\/wp-content\/uploads\/sites\/23\/2020\/07\/2000ouvintes_1_original-1-768x403.jpg 768w, https:\/\/blog.panrotas.com.br\/mktdestinos\/wp-content\/uploads\/sites\/23\/2020\/07\/2000ouvintes_1_original-1-740x389.jpg 740w, https:\/\/blog.panrotas.com.br\/mktdestinos\/wp-content\/uploads\/sites\/23\/2020\/07\/2000ouvintes_1_original-1.jpg 1200w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p>J\u00e1 experimentou ouvir as lideran\u00e7as de turismo no nosso <a href=\"https:\/\/open.spotify.com\/show\/53AMkbIVDPNa9f4a6kXSeJ?si=L9YCz_4AR3q-ZIygoorMEw\">podcast HUB TURISMO<\/a>? Estamos com mais de 2 mil ouvintes, passa por l\u00e1, segue a gente e compartilha com seus amigos e colegas. A sele\u00e7\u00e3o que fiz para voc\u00ea traz 3 conversas super antenadas e atuais:<\/p>\n\n\n\n<p>1- Dados da<a href=\"https:\/\/amadeus.com\/en\"> Amadeus<\/a> mostram impactos nas viagens, cen\u00e1rios de recupera\u00e7\u00e3o do turismo e tecnologias que ser\u00e3o grandes aliadas do setor. <a href=\"http:\/\/linkedin.com\/in\/paulo-rezende-67481a7\">Paulo Rezende<\/a> analisa ainda a confian\u00e7a e a humaniza\u00e7\u00e3o das viagens, comportamento do consumidor e nos fala sobre a diversidade na atua\u00e7\u00e3o da Amadeus em diversos segmentos da ind\u00fastria. <a href=\"https:\/\/amadeus.com\/pt\/insights\">Aqui voc\u00ea encontra mais insights e estudos da Amadeus<\/a>.<\/p>\n\n\n\n<figure class=\"wp-block-embed-spotify wp-block-embed is-type-rich is-provider-spotify wp-embed-aspect-21-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"Spotify Embed: HUB 19: Bate-papo com Paulo Rezende da Amadeus\" width=\"100%\" height=\"232\" allowtransparency=\"true\" frameborder=\"0\" allow=\"encrypted-media\" src=\"https:\/\/open.spotify.com\/embed-podcast\/episode\/6IZuDTjhykelzIO4b0BRRX\"><\/iframe>\n<\/div><\/figure>\n\n\n\n<p>2- Como empres\u00e1rios est\u00e3o vendo o atual cen\u00e1rio do Brasil e encontrando formas de coopera\u00e7\u00e3o para seguir adiante em suas empresas; <a href=\"http:\/\/linkedin.com\/in\/aldoagaxtur\">Aldo Leone Filho<\/a>, CEO da <a href=\"https:\/\/www.agaxturviagens.com.br\/?gclid=Cj0KCQjw6uT4BRD5ARIsADwJQ1-5PFxxJoM96pBQPBQaxBqpv5ZOCtzQftwkuw2T7FMj0LBQJEU1LokaAuxjEALw_wcB\">AGAXTUR<\/a>, fala sobre o tema, sobre o <a href=\"https:\/\/movimentosuperaturismo.com.br\">MOVIMENTO SUPERA TURISMO<\/a>, a confian\u00e7a nas viagens e o papel das ag\u00eancias de viagens.<\/p>\n\n\n\n<figure class=\"wp-block-embed-spotify wp-block-embed is-type-rich is-provider-spotify wp-embed-aspect-21-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"Spotify Embed: HUB 20: Bate-papo com Aldo Leone Filho\" width=\"100%\" height=\"232\" allowtransparency=\"true\" frameborder=\"0\" allow=\"encrypted-media\" src=\"https:\/\/open.spotify.com\/embed-podcast\/episode\/1kM1QJR0Z7ry6yD1ks4OI0\"><\/iframe>\n<\/div><\/figure>\n\n\n\n<p>3- J\u00e1 pensou em como redefinir sua estrat\u00e9gia de marketing digital? Voc\u00ea n\u00e3o tem uma estrat\u00e9gia? Como alinhar seu digital se voc\u00ea tem empresa de turismo ou \u00e9 profissional de destinos? Como ficam os influenciadores digitais, o planejamento e a import\u00e2ncia de estar no on-line de forma multicanais. <a href=\"http:\/\/linkedin.com\/in\/jaderson-de-alencar-1039b318\">Jaderson de Alencar<\/a> \u00e9 Diretor de Comunica\u00e7\u00e3o Digital Estrat\u00e9gica da <a href=\"https:\/\/www.fsb.com.br\">FSB COMUNICA\u00c7\u00c3O<\/a> e bate um papo sobre todos esses temas e muito mais.<\/p>\n\n\n\n<figure class=\"wp-block-embed-spotify wp-block-embed is-type-rich is-provider-spotify wp-embed-aspect-21-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"Spotify Embed: HUB 15: Marketing digital em turismo com Jaderson Alencar\" width=\"100%\" height=\"232\" allowtransparency=\"true\" frameborder=\"0\" allow=\"encrypted-media\" src=\"https:\/\/open.spotify.com\/embed-podcast\/episode\/3mCh6ZWDKt1xjqtgz6arTZ\"><\/iframe>\n<\/div><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>J\u00e1 experimentou ouvir as lideran\u00e7as de turismo no nosso podcast HUB TURISMO? Estamos com mais de 2 mil ouvintes, passa por l\u00e1, segue a gente e compartilha com seus amigos e colegas. A sele\u00e7\u00e3o que fiz para voc\u00ea traz 3 conversas super antenadas e atuais: 1- Dados da Amadeus mostram impactos nas viagens, cen\u00e1rios de&hellip; <a class=\"more-link\" href=\"https:\/\/blog.panrotas.com.br\/mktdestinos\/2020\/07\/23\/3-papos-imperdiveis\/\">Continue reading &rarr;<\/a><\/p>\n","protected":false},"author":21,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[1],"tags":[18,1151,1152,46,1150,547,1153],"_links":{"self":[{"href":"https:\/\/blog.panrotas.com.br\/mktdestinos\/wp-json\/wp\/v2\/posts\/3388"}],"collection":[{"href":"https:\/\/blog.panrotas.com.br\/mktdestinos\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.panrotas.com.br\/mktdestinos\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog.panrotas.com.br\/mktdestinos\/wp-json\/wp\/v2\/users\/21"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.panrotas.com.br\/mktdestinos\/wp-json\/wp\/v2\/comments?post=3388"}],"version-history":[{"count":4,"href":"https:\/\/blog.panrotas.com.br\/mktdestinos\/wp-json\/wp\/v2\/posts\/3388\/revisions"}],"predecessor-version":[{"id":3395,"href":"https:\/\/blog.panrotas.com.br\/mktdestinos\/wp-json\/wp\/v2\/posts\/3388\/revisions\/3395"}],"wp:attachment":[{"href":"https:\/\/blog.panrotas.com.br\/mktdestinos\/wp-json\/wp\/v2\/media?parent=3388"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.panrotas.com.br\/mktdestinos\/wp-json\/wp\/v2\/categories?post=3388"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.panrotas.com.br\/mktdestinos\/wp-json\/wp\/v2\/tags?post=3388"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}